{"id":67181,"date":"2024-01-30T11:33:40","date_gmt":"2024-01-30T10:33:40","guid":{"rendered":"https:\/\/www.expertea.fr\/?page_id=67181"},"modified":"2024-01-30T11:33:40","modified_gmt":"2024-01-30T10:33:40","slug":"temoignages","status":"publish","type":"page","link":"https:\/\/www.expertea.fr\/en\/temoignages\/","title":{"rendered":"T\u00e9moignages"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-67181","page","type-page","status-publish","hentry","page_category-expertea-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9moignages - Expertea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expertea.fr\/en\/temoignages\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9moignages - Expertea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expertea.fr\/en\/temoignages\/\" \/>\n<meta property=\"og:site_name\" content=\"Expertea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.expertea.fr\\\/en\\\/temoignages\\\/\",\"url\":\"https:\\\/\\\/www.expertea.fr\\\/en\\\/temoignages\\\/\",\"name\":\"T\u00e9moignages - Expertea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.expertea.fr\\\/#website\"},\"datePublished\":\"2024-01-30T10:33:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.expertea.fr\\\/en\\\/temoignages\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.expertea.fr\\\/en\\\/temoignages\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.expertea.fr\\\/en\\\/temoignages\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.expertea.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9moignages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.expertea.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.expertea.fr\\\/\",\"name\":\"Expertea\",\"description\":\"Audit - Expertise - Conseil\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.expertea.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9moignages - Expertea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expertea.fr\/en\/temoignages\/","og_locale":"en_US","og_type":"article","og_title":"T\u00e9moignages - Expertea","og_url":"https:\/\/www.expertea.fr\/en\/temoignages\/","og_site_name":"Expertea","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expertea.fr\/en\/temoignages\/","url":"https:\/\/www.expertea.fr\/en\/temoignages\/","name":"T\u00e9moignages - Expertea","isPartOf":{"@id":"https:\/\/www.expertea.fr\/#website"},"datePublished":"2024-01-30T10:33:40+00:00","breadcrumb":{"@id":"https:\/\/www.expertea.fr\/en\/temoignages\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expertea.fr\/en\/temoignages\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.expertea.fr\/en\/temoignages\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.expertea.fr\/en\/"},{"@type":"ListItem","position":2,"name":"T\u00e9moignages"}]},{"@type":"WebSite","@id":"https:\/\/www.expertea.fr\/#website","url":"https:\/\/www.expertea.fr\/","name":"Expertea","description":"Audit - Expertise - Conseil","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expertea.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/pages\/67181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/comments?post=67181"}],"version-history":[{"count":1,"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/pages\/67181\/revisions"}],"predecessor-version":[{"id":67182,"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/pages\/67181\/revisions\/67182"}],"wp:attachment":[{"href":"https:\/\/www.expertea.fr\/en\/wp-json\/wp\/v2\/media?parent=67181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}